{"id":108658,"date":"2026-03-04T18:05:53","date_gmt":"2026-03-04T18:05:53","guid":{"rendered":"https:\/\/matchbaits.pt\/?post_type=product&#038;p=108658"},"modified":"2026-08-11T09:10:30","modified_gmt":"2026-08-11T09:10:30","slug":"mf-delannoy","status":"publish","type":"product","link":"https:\/\/sopesca.pt\/fr\/produit\/mf-delannoy\/","title":{"rendered":"MF Delannoy"},"content":{"rendered":"<h2>MF Delannoy<\/h2>\n<p>Uma boia de corpo ostilizado construida em bal\u00e7a e pena de pav\u00e3o<br \/>\nVarias antenas para aumentar a capacidade de vizibilidade<br \/>\nO formato do seu corpo permite lan\u00e7amentos longos ao mesmo tempo que \u00e9 muito sensivel<br \/>\nDispon\u00edvel em 10\/12\/14\/16\/18\/20g<\/p>","protected":false},"excerpt":{"rendered":"<p>MF Delannoy Uma boia de corpo ostilizado construida em bal\u00e7a e pena de pav\u00e3o Varias antenas para aumentar a capacidade de vizibilidade O formato do seu corpo permite lan\u00e7amentos longos ao mesmo tempo que \u00e9 muito sensivel Dispon\u00edvel em 10\/12\/14\/16\/18\/20g<\/p>","protected":false},"featured_media":108667,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[2814,704],"product_cat":[2267,2306],"product_tag":[],"class_list":["post-108658","product","type-product","status-publish","has-post-thumbnail","product_brand-matchbaits","product_brand-matchfloat","product_cat-boias","product_cat-boias-inglesa","first","instock","shipping-taxable","purchasable","product-type-variable"],"acf":[],"_links":{"self":[{"href":"https:\/\/sopesca.pt\/fr\/wp-json\/wp\/v2\/product\/108658","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sopesca.pt\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/sopesca.pt\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/sopesca.pt\/fr\/wp-json\/wp\/v2\/comments?post=108658"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sopesca.pt\/fr\/wp-json\/wp\/v2\/media\/108667"}],"wp:attachment":[{"href":"https:\/\/sopesca.pt\/fr\/wp-json\/wp\/v2\/media?parent=108658"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/sopesca.pt\/fr\/wp-json\/wp\/v2\/product_brand?post=108658"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/sopesca.pt\/fr\/wp-json\/wp\/v2\/product_cat?post=108658"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/sopesca.pt\/fr\/wp-json\/wp\/v2\/product_tag?post=108658"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}